{"id":1474,"date":"2022-10-14T15:59:37","date_gmt":"2022-10-14T13:59:37","guid":{"rendered":"https:\/\/ecorav.com\/?p=1474"},"modified":"2022-10-14T16:01:34","modified_gmt":"2022-10-14T14:01:34","slug":"presenti-allecomondo-2022","status":"publish","type":"post","link":"https:\/\/www.ecorav.com\/en\/presenti-allecomondo-2022\/","title":{"rendered":"Presenti all\u2019Ecomondo 2022"},"content":{"rendered":"<p class=\"x_MsoNormal\">Dall\u20198 all\u201911 novembre parteciperemo ad una delle Fiere internazionali di riferimento per tutti i settori dell\u2019economia circolare: l\u2019Ecomondo, nel quartiere fieristico di Rimini.<\/p>\n<p class=\"x_MsoNormal\">Un\u2019opportunit\u00e0 che desideriamo cogliere per raccontare le nostre evoluzioni e le nostre visioni, per continuare a costruire un confronto stimolante con i clienti, per guardare un po\u2019 pi\u00f9 lontano.<\/p>\n<p class=\"x_MsoNormal\">Abbiamo tante novit\u00e0 da condividere.<\/p>\n<p class=\"x_MsoNormal\">Vi aspettiamo al padiglione C3, stand 092.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dall\u20198 all\u201911 novembre parteciperemo ad una delle Fiere internazionali di riferimento per tutti i settori dell\u2019economia circolare: l\u2019Ecomondo, nel quartiere fieristico di Rimini. Un\u2019opportunit\u00e0 che desideriamo cogliere per raccontare le nostre evoluzioni e le nostre visioni, per continuare a costruire un confronto stimolante con i clienti, per guardare un po\u2019 pi\u00f9 lontano. Abbiamo tante novit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria"],"_links":{"self":[{"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/posts\/1474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/comments?post=1474"}],"version-history":[{"count":1,"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/posts\/1474\/revisions"}],"predecessor-version":[{"id":1476,"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/posts\/1474\/revisions\/1476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/media\/1477"}],"wp:attachment":[{"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/media?parent=1474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/categories?post=1474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ecorav.com\/en\/wp-json\/wp\/v2\/tags?post=1474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}